{"id":68170,"date":"2023-04-21T15:14:24","date_gmt":"2023-04-21T13:14:24","guid":{"rendered":"https:\/\/ehrler-beck.tiaro.eu\/?post_type=beundeh_portfolio&#038;p=68170"},"modified":"2023-04-21T15:14:24","modified_gmt":"2023-04-21T13:14:24","slug":"roto-synthetic-fluid-ultra-209l","status":"publish","type":"tirenoa_portfolio","link":"https:\/\/ehrler-beck.com\/es\/produkt\/roto-synthetic-fluid-ultra-209l","title":{"rendered":"Fluido Sint\u00e9tico Roto ULTRA 209l"},"content":{"rendered":"<p>Vertrauen Sie auf das Roto Synthetic Fluid ULTRA 209l (1630 2041 29) von Atlas Copco, erh\u00e4ltlich bei Ehrler und Beck, f\u00fcr anspruchsvolle Anwendungen und beste Leistung Ihrer Kompressoren. Dieses hochwertige synthetische \u00d6l bietet erweiterte Wartungsintervalle von bis zu 4.000 Stunden, auch unter schwierigen Bedingungen, und gew\u00e4hrleistet einen effizienten Betrieb Ihrer Kompressoren in staubigen und feuchten Umgebungen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Vertrauen Sie auf das Roto Synthetic Fluid ULTRA 209l (1630 2041 29) von Atlas Copco, erh\u00e4ltlich bei Ehrler und Beck, f\u00fcr anspruchsvolle Anwendungen und beste Leistung Ihrer Kompressoren. Dieses hochwertige synthetische \u00d6l bietet erweiterte Wartungsintervalle von bis zu 4.000 Stunden, auch unter schwierigen Bedingungen, und gew\u00e4hrleistet einen effizienten Betrieb Ihrer Kompressoren in staubigen und feuchten Umgebungen.<\/p>","protected":false},"author":1,"featured_media":68163,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[2664],"portfolio_skills":[554],"portfolio_tags":[2583,2658],"class_list":["post-68170","tirenoa_portfolio","type-tirenoa_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-roto-synthetic-fluid-ultra","portfolio_skills-atlas-copco","portfolio_tags-oele-und-fette","portfolio_tags-synthetisches-schmiermittel"],"acf":[],"_links":{"self":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/tirenoa_portfolio\/68170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/tirenoa_portfolio"}],"about":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/types\/tirenoa_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/comments?post=68170"}],"version-history":[{"count":0,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/tirenoa_portfolio\/68170\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/media\/68163"}],"wp:attachment":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/media?parent=68170"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/portfolio_category?post=68170"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/portfolio_skills?post=68170"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/portfolio_tags?post=68170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}