{"id":64267,"date":"2022-09-17T14:27:59","date_gmt":"2022-09-17T12:27:59","guid":{"rendered":"https:\/\/ehrler-beck.tiaro.eu\/?post_type=beundeh_portfolio&#038;p=64267"},"modified":"2022-09-17T15:52:00","modified_gmt":"2022-09-17T13:52:00","slug":"control-deslizante-971424540","status":"publish","type":"tirenoa_portfolio","link":"https:\/\/ehrler-beck.com\/es\/produkt\/schieber-971424540","title":{"rendered":"Control deslizante 971424540"},"content":{"rendered":"<p><span style=\"font-size: 14pt;\">Juego de correderas Leybold original SOGEVAC SV 630 B \u2013 971424540. El juego contiene 3 correderas de carbono.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Los controles deslizantes est\u00e1n sujetos a desgaste. Las paletas deben cambiarse peri\u00f3dicamente seg\u00fan las instrucciones de funcionamiento de la bomba a la que est\u00e1n destinadas.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Original Leybold Schieber Set SOGEVAC SV 630 B &#8211; 971424540. Satz enth\u00e4lt 3 kohleschieber. Schieber Sie unterliegen einem Verschlei\u00df. Schieber m\u00fcssen gem\u00e4\u00df der Betriebsanleitung der Pumpe, f\u00fcr die sie bestimmt sind, regelm\u00e4\u00dfig gewechselt werden.<\/p>","protected":false},"author":1,"featured_media":64268,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[2563],"portfolio_skills":[438],"portfolio_tags":[2506],"class_list":["post-64267","tirenoa_portfolio","type-tirenoa_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-sogevac-sv-630-b","portfolio_skills-leybold-produkte","portfolio_tags-schieber"],"acf":[],"_links":{"self":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/tirenoa_portfolio\/64267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/tirenoa_portfolio"}],"about":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/types\/tirenoa_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/comments?post=64267"}],"version-history":[{"count":0,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/tirenoa_portfolio\/64267\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/media\/64268"}],"wp:attachment":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/media?parent=64267"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/portfolio_category?post=64267"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/portfolio_skills?post=64267"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/portfolio_tags?post=64267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}