{"id":61874,"date":"2022-08-11T13:09:42","date_gmt":"2022-08-11T11:09:42","guid":{"rendered":"https:\/\/ehrler-beck.tiaro.eu\/?post_type=beundeh_portfolio&#038;p=61874"},"modified":"2022-08-11T13:18:57","modified_gmt":"2022-08-11T11:18:57","slug":"g-bh1-2bh1-100-soplador","status":"publish","type":"tirenoa_portfolio","link":"https:\/\/ehrler-beck.com\/es\/produkt\/g-bh1-2bh1-100-geblaese","title":{"rendered":"G-BH1 2BH1 100 sopladores"},"content":{"rendered":"<p>El soplador G-BH1 100 es fiable, duradero y requiere poco mantenimiento. Los sopladores G-BH1 tienen un alto caudal de aspiraci\u00f3n de hasta 2.500 m\u00b3\/h y una presi\u00f3n diferencial de hasta 780 mbar. Los sopladores de canal lateral G-BH1 de Elmo Rietschle se han ganado su reputaci\u00f3n. Los sopladores de la serie G-BH1 pueden proporcionar hasta 20.000 horas de funcionamiento sin problemas.<\/p>","protected":false},"excerpt":{"rendered":"<p>El soplador G-BH1 100 es fiable, duradero y requiere poco mantenimiento. Los sopladores G-BH1 tienen un alto caudal de aspiraci\u00f3n de hasta 2.500 m\u00b3\/h y una presi\u00f3n diferencial de hasta 780 mbar. Los sopladores de canal lateral G-BH1 de Elmo Rietschle se han ganado su reputaci\u00f3n. Los sopladores de la serie G-BH1 pueden proporcionar hasta 20.000 horas de funcionamiento sin problemas.<\/p>","protected":false},"author":1,"featured_media":61875,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[923],"portfolio_skills":[441],"portfolio_tags":[924,1965],"class_list":["post-61874","tirenoa_portfolio","type-tirenoa_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-g-serie","portfolio_skills-elmo-rietschle-produkte","portfolio_tags-seitenkanal-vakuumpumpen","portfolio_tags-seitenkanal-verdichter"],"acf":[],"_links":{"self":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/tirenoa_portfolio\/61874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/tirenoa_portfolio"}],"about":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/types\/tirenoa_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/comments?post=61874"}],"version-history":[{"count":0,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/tirenoa_portfolio\/61874\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/media\/61875"}],"wp:attachment":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/media?parent=61874"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/portfolio_category?post=61874"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/portfolio_skills?post=61874"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/portfolio_tags?post=61874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}