{"id":60972,"date":"2022-08-08T13:07:05","date_gmt":"2022-08-08T11:07:05","guid":{"rendered":"https:\/\/ehrler-beck.tiaro.eu\/?post_type=beundeh_portfolio&#038;p=60972"},"modified":"2022-08-08T14:26:37","modified_gmt":"2022-08-08T12:26:37","slug":"k05-ts-geblaese","status":"publish","type":"tirenoa_portfolio","link":"https:\/\/ehrler-beck.com\/es\/produkt\/k05-ts-geblaese","title":{"rendered":"Soplador K05-TS"},"content":{"rendered":"<p>K05-TS-Gebl\u00e4se bieten Doppelimpeller an \u2013 doppelte Stufe, integrale Bewegungsauslegungversionen, Aluminiumaufbau. Zweipolige Elektromotoren, einphasig und dreiphasig asynchron, Isolationsklasse F-Tropicalized und IP55-Schutz.<\/p>","protected":false},"excerpt":{"rendered":"<p>K05-TS-Gebl\u00e4se bieten Doppelimpeller an \u2013 doppelte Stufe, integrale Bewegungsauslegungversionen, Aluminiumaufbau. Zweipolige Elektromotoren, einphasig und dreiphasig asynchron, Isolationsklasse F-Tropicalized und IP55-Schutz.<\/p>","protected":false},"author":1,"featured_media":61017,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[1970],"portfolio_skills":[1966],"portfolio_tags":[924,1965],"class_list":["post-60972","tirenoa_portfolio","type-tirenoa_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-ms-ts-md-td-serie","portfolio_skills-fpz","portfolio_tags-seitenkanal-vakuumpumpen","portfolio_tags-seitenkanal-verdichter"],"acf":[],"_links":{"self":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/tirenoa_portfolio\/60972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/tirenoa_portfolio"}],"about":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/types\/tirenoa_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/comments?post=60972"}],"version-history":[{"count":0,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/tirenoa_portfolio\/60972\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/media\/61017"}],"wp:attachment":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/media?parent=60972"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/portfolio_category?post=60972"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/portfolio_skills?post=60972"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/portfolio_tags?post=60972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}