{"id":60687,"date":"2022-08-07T13:08:07","date_gmt":"2022-08-07T11:08:07","guid":{"rendered":"https:\/\/ehrler-beck.tiaro.eu\/?post_type=beundeh_portfolio&#038;p=60687"},"modified":"2022-08-07T13:08:07","modified_gmt":"2022-08-07T11:08:07","slug":"ruvac-wau-251-bomba-de-vacio","status":"publish","type":"tirenoa_portfolio","link":"https:\/\/ehrler-beck.com\/es\/produkt\/ruvac-wau-251-vakuumpumpe","title":{"rendered":"Bomba de vac\u00edo RUVAC WAU 251"},"content":{"rendered":"<p>RUVAC WAU 251 es una bomba de vac\u00edo de ra\u00edz enfriada por aire confiable. Todas las bombas WAU cumplen de serie con la categor\u00eda 3i de ATEX. Las bombas de vac\u00edo RUVAC WAU Root se suministran como est\u00e1ndar para acci\u00f3n de bombeo vertical, acci\u00f3n de bombeo horizontal a pedido.<\/p>","protected":false},"excerpt":{"rendered":"<p>RUVAC WAU 251 es una bomba de vac\u00edo de ra\u00edz enfriada por aire confiable. Todas las bombas WAU cumplen de serie con la categor\u00eda 3i de ATEX. Las bombas de vac\u00edo RUVAC WAU Root se suministran como est\u00e1ndar para acci\u00f3n de bombeo vertical, acci\u00f3n de bombeo horizontal a pedido.<\/p>","protected":false},"author":1,"featured_media":60657,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[1910],"portfolio_skills":[438],"portfolio_tags":[930],"class_list":["post-60687","tirenoa_portfolio","type-tirenoa_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-ruvac-serie","portfolio_skills-leybold-produkte","portfolio_tags-waelzkolben-vakuumpumpen"],"acf":[],"_links":{"self":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/tirenoa_portfolio\/60687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/tirenoa_portfolio"}],"about":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/types\/tirenoa_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/comments?post=60687"}],"version-history":[{"count":0,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/tirenoa_portfolio\/60687\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/media\/60657"}],"wp:attachment":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/media?parent=60687"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/portfolio_category?post=60687"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/portfolio_skills?post=60687"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/portfolio_tags?post=60687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}