{"id":54147,"date":"2022-05-09T16:08:30","date_gmt":"2022-05-09T14:08:30","guid":{"rendered":"https:\/\/ehrler-beck.tiaro.eu\/?post_type=beundeh_portfolio&#038;p=54147"},"modified":"2022-08-04T19:59:52","modified_gmt":"2022-08-04T17:59:52","slug":"sv-200-1-seitenkanal-vakuumpumpen","status":"publish","type":"tirenoa_portfolio","link":"https:\/\/ehrler-beck.com\/es\/produkt\/sv-200-1-seitenkanal-vakuumpumpen","title":{"rendered":"Bombas de vac\u00edo de canal lateral SV 200\/1"},"content":{"rendered":"<p>Das SV 200\/1 ist ein einstufiges regeneratives Gebl\u00e4se, das hohe Leistung in einer ruhigen, ber\u00fchrungslosen Umgebung bietet. 100 % \u00f6l- und ber\u00fchrungsfrei im Betrieb sind diese Pumpen wartungsarm, hocheffizient und ben\u00f6tigen nur minimale Wartung.<\/p>","protected":false},"excerpt":{"rendered":"<p>Das SV 200\/1 ist ein einstufiges regeneratives Gebl\u00e4se, das hohe Leistung in einer ruhigen, ber\u00fchrungslosen Umgebung bietet. 100 % \u00f6l- und ber\u00fchrungsfrei im Betrieb sind diese Pumpen wartungsarm, hocheffizient und ben\u00f6tigen nur minimale Wartung.<\/p>","protected":false},"author":1,"featured_media":54151,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[1613],"portfolio_skills":[437],"portfolio_tags":[924],"class_list":["post-54147","tirenoa_portfolio","type-tirenoa_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-sv-serie","portfolio_skills-becker","portfolio_tags-seitenkanal-vakuumpumpen"],"acf":[],"_links":{"self":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/tirenoa_portfolio\/54147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/tirenoa_portfolio"}],"about":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/types\/tirenoa_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/comments?post=54147"}],"version-history":[{"count":0,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/tirenoa_portfolio\/54147\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/media\/54151"}],"wp:attachment":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/media?parent=54147"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/portfolio_category?post=54147"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/portfolio_skills?post=54147"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/portfolio_tags?post=54147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}