{"id":18055,"date":"2019-03-22T06:12:50","date_gmt":"2019-03-22T05:12:50","guid":{"rendered":"https:\/\/ehrler-beck.tiaro.eu\/?post_type=avada_portfolio&#038;p=18055"},"modified":"2024-02-01T07:52:40","modified_gmt":"2024-02-01T06:52:40","slug":"r5-ra-0205-d-vakuumpumpe","status":"publish","type":"tirenoa_portfolio","link":"https:\/\/ehrler-beck.com\/es\/produkt\/r5-ra-0205-d-vakuumpumpe","title":{"rendered":"Bomba de vac\u00edo R5 RA 0205 D"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Robuster und zuverl\u00e4ssiger Betrieb sind die herausragenden Merkmale der Vakuumpumpe R5 RA 0205 D. Es ist speziell f\u00fcr Anwendungen im Grobvakuum Bereich konzipiert worden. Aufgrund der hohen Abscheideleistung wird auch unter schwierigen Bedingungen \u00f6lfreie Abluft erzeugt. Entworfen von BUSCH f\u00fcr kontinuierlichen Betrieb bei niedrigen Betriebskosten.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Robuster und zuverl\u00e4ssiger Betrieb sind die herausragenden Merkmale der Vakuumpumpe R5 RA 0205 D. Es ist speziell f\u00fcr Anwendungen im Grobvakuum Bereich<\/p>","protected":false},"author":1,"featured_media":18071,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[433],"portfolio_skills":[439],"portfolio_tags":[548],"class_list":["post-18055","tirenoa_portfolio","type-tirenoa_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-r5-serie","portfolio_skills-busch-produkte","portfolio_tags-drehschieber-vakuumpumpen-olgeschmiert"],"acf":[],"_links":{"self":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/tirenoa_portfolio\/18055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/tirenoa_portfolio"}],"about":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/types\/tirenoa_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/comments?post=18055"}],"version-history":[{"count":0,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/tirenoa_portfolio\/18055\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/media\/18071"}],"wp:attachment":[{"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/media?parent=18055"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/portfolio_category?post=18055"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/portfolio_skills?post=18055"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/ehrler-beck.com\/es\/wp-json\/wp\/v2\/portfolio_tags?post=18055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}