{"id":61651,"date":"2022-08-09T11:59:55","date_gmt":"2022-08-09T09:59:55","guid":{"rendered":"https:\/\/ehrler-beck.tiaro.eu\/?post_type=beundeh_portfolio&#038;p=61651"},"modified":"2022-08-09T11:59:55","modified_gmt":"2022-08-09T09:59:55","slug":"sd-92-geblaese","status":"publish","type":"tirenoa_portfolio","link":"https:\/\/ehrler-beck.com\/en\/produkt\/sd-92-geblaese","title":{"rendered":"SD 92 blower"},"content":{"rendered":"<p>Der SD 92 bietet an ber\u00fchrungsfrei laufende Druck- und Vakuumerzeuger, ger\u00e4uschged\u00e4mpft, wartungsfrei, kompakt, absolut \u00f6l frei, energie- und Kostenersparnis durch optimierte Anwendungen, Ger\u00e4te werden schonender betrieben, dadurch Verlagerung der Lebensdauer, keine unn\u00f6tige Ger\u00e4uschbelastung und W\u00e4rmeentwicklung.<\/p>","protected":false},"excerpt":{"rendered":"<p>Der SD 92 bietet an ber\u00fchrungsfrei laufende Druck- und Vakuumerzeuger, ger\u00e4uschged\u00e4mpft, wartungsfrei, kompakt, absolut \u00f6l frei, energie- und Kostenersparnis durch optimierte Anwendungen, Ger\u00e4te werden schonender betrieben, dadurch Verlagerung der Lebensdauer, keine unn\u00f6tige Ger\u00e4uschbelastung und W\u00e4rmeentwicklung.<\/p>","protected":false},"author":1,"featured_media":61598,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[2128],"portfolio_skills":[1825],"portfolio_tags":[924,1965],"class_list":["post-61651","tirenoa_portfolio","type-tirenoa_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-sd-serie","portfolio_skills-elektror","portfolio_tags-seitenkanal-vakuumpumpen","portfolio_tags-seitenkanal-verdichter"],"acf":[],"_links":{"self":[{"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/tirenoa_portfolio\/61651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/tirenoa_portfolio"}],"about":[{"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/types\/tirenoa_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/comments?post=61651"}],"version-history":[{"count":0,"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/tirenoa_portfolio\/61651\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/media\/61598"}],"wp:attachment":[{"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/media?parent=61651"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/portfolio_category?post=61651"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/portfolio_skills?post=61651"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/portfolio_tags?post=61651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}