{"id":59554,"date":"2022-08-04T17:05:36","date_gmt":"2022-08-04T15:05:36","guid":{"rendered":"https:\/\/ehrler-beck.tiaro.eu\/?post_type=beundeh_portfolio&#038;p=59554"},"modified":"2022-08-04T17:05:36","modified_gmt":"2022-08-04T15:05:36","slug":"2d-060-vakuumpumpe","status":"publish","type":"tirenoa_portfolio","link":"https:\/\/ehrler-beck.com\/en\/produkt\/2d-060-vakuumpumpe","title":{"rendered":"2D 060 vacuum pump"},"content":{"rendered":"<p>Elektror-Niederdruckventilatoren 2D 060 bieten Einbaufertige Ausf\u00fchrung mit Drehstromoder Einphasen-Wechselstrom-Motoren, Hohes Leistungsverm\u00f6gen bei kompakter Bauweise, Lange Nutzungsdauer bei niedrigen Betriebskosten, Gute Wirkungsgrade, G\u00fcnstiges Ger\u00e4uschverhalten, Zweckm\u00e4\u00dfiges Zubeh\u00f6r.<\/p>","protected":false},"excerpt":{"rendered":"<p>Elektror-Niederdruckventilatoren 2D 060 bieten Einbaufertige Ausf\u00fchrung mit Drehstromoder Einphasen-Wechselstrom-Motoren, Hohes Leistungsverm\u00f6gen bei kompakter Bauweise, Lange Nutzungsdauer bei niedrigen Betriebskosten, Gute Wirkungsgrade, G\u00fcnstiges Ger\u00e4uschverhalten, Zweckm\u00e4\u00dfiges Zubeh\u00f6r.<\/p>","protected":false},"author":1,"featured_media":59515,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[1826],"portfolio_skills":[1825],"portfolio_tags":[1790],"class_list":["post-59554","tirenoa_portfolio","type-tirenoa_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-nd-serie","portfolio_skills-elektror","portfolio_tags-radial-vakuumpumpen"],"acf":[],"_links":{"self":[{"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/tirenoa_portfolio\/59554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/tirenoa_portfolio"}],"about":[{"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/types\/tirenoa_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/comments?post=59554"}],"version-history":[{"count":0,"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/tirenoa_portfolio\/59554\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/media\/59515"}],"wp:attachment":[{"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/media?parent=59554"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/portfolio_category?post=59554"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/portfolio_skills?post=59554"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/portfolio_tags?post=59554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}