{"id":54009,"date":"2022-05-08T20:34:37","date_gmt":"2022-05-08T18:34:37","guid":{"rendered":"https:\/\/ehrler-beck.com\/?post_type=beundeh_portfolio&#038;p=54009"},"modified":"2022-05-08T20:34:37","modified_gmt":"2022-05-08T18:34:37","slug":"elr-950i-vakuumpumpe","status":"publish","type":"collagea_portfolio","link":"https:\/\/ehrler-beck.com\/en\/produkt\/elr-950i-vacuum-pump","title":{"rendered":"ELR 950i Vakuumpumpe"},"content":{"rendered":"<p>Die ELRI-Baureihe umfasst einstufige, intelligente Vakuumpumpen mit vollst\u00e4ndiger R\u00fcckgewinnung, die auf bew\u00e4hrter Technologie basieren und im klug zusammengestellten Paket geliefert werden. Zuverl\u00e4ssigkeit und geringer Wartungsaufwand dieser auf Langlebigkeit ausgelegten Pumpen machen sie zur besten L\u00f6sung, wenn es um das Pumpen von feuchten Gasen oder Partikeln geht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die ELRI-Baureihe umfasst einstufige, intelligente Vakuumpumpen mit vollst\u00e4ndiger R\u00fcckgewinnung, die auf bew\u00e4hrter Technologie basieren und im klug zusammengestellten Paket geliefert werden. Zuverl\u00e4ssigkeit und geringer Wartungsaufwand dieser auf Langlebigkeit ausgelegten Pumpen machen sie zur besten L\u00f6sung, wenn es um das Pumpen von feuchten Gasen oder Partikeln geht.<\/p>\n","protected":false},"author":1,"featured_media":53980,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"footnotes":""},"portfolio_number":[1604,1605],"portfolio_category":[1601],"portfolio_skills":[538],"portfolio_tags":[840],"class_list":["post-54009","collagea_portfolio","type-collagea_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_number-a75167101","portfolio_number-a75167111","portfolio_category-elri-serie","portfolio_skills-edwards-produkte","portfolio_tags-fluessigkeitsring-vakuumpumpen"],"acf":[],"_links":{"self":[{"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/collagea_portfolio\/54009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/collagea_portfolio"}],"about":[{"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/types\/collagea_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/comments?post=54009"}],"version-history":[{"count":1,"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/collagea_portfolio\/54009\/revisions"}],"predecessor-version":[{"id":54010,"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/collagea_portfolio\/54009\/revisions\/54010"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/media\/53980"}],"wp:attachment":[{"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/media?parent=54009"}],"wp:term":[{"taxonomy":"portfolio_number","embeddable":true,"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/portfolio_number?post=54009"},{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/portfolio_category?post=54009"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/portfolio_skills?post=54009"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/ehrler-beck.com\/en\/wp-json\/wp\/v2\/portfolio_tags?post=54009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}