{"id":64287,"date":"2022-09-17T14:36:41","date_gmt":"2022-09-17T12:36:41","guid":{"rendered":"https:\/\/ehrler-beck.tiaro.eu\/?post_type=beundeh_portfolio&#038;p=64287"},"modified":"2022-09-17T15:52:47","modified_gmt":"2022-09-17T13:52:47","slug":"schieber-71416750","status":"publish","type":"tirenoa_portfolio","link":"https:\/\/ehrler-beck.com\/de\/produkt\/schieber-71416750","title":{"rendered":"Schieber 71416750"},"content":{"rendered":"<p><span style=\"font-size: 14pt;\">Original Leybold Schieber Set SOGEVAC SV 65 B &#8211; 71416750. Satz enth\u00e4lt 3 kohleschieber.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Schieber Sie unterliegen einem Verschlei\u00df. Schieber m\u00fcssen gem\u00e4\u00df der Betriebsanleitung der Pumpe, f\u00fcr die sie bestimmt sind, regelm\u00e4\u00dfig gewechselt werden.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Original Leybold Schieber Set SOGEVAC SV 65 B &#8211; 71416750. Satz enth\u00e4lt 3 kohleschieber. Schieber Sie unterliegen einem Verschlei\u00df. Schieber m\u00fcssen gem\u00e4\u00df der Betriebsanleitung der Pumpe, f\u00fcr die sie bestimmt sind, regelm\u00e4\u00dfig gewechselt werden.<\/p>\n","protected":false},"author":1,"featured_media":64288,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[2552],"portfolio_skills":[438],"portfolio_tags":[2506],"class_list":["post-64287","tirenoa_portfolio","type-tirenoa_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-sogevac-sv-65-b","portfolio_skills-leybold-produkte","portfolio_tags-schieber"],"acf":[],"_links":{"self":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio\/64287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio"}],"about":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/types\/tirenoa_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/comments?post=64287"}],"version-history":[{"count":0,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio\/64287\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/media\/64288"}],"wp:attachment":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/media?parent=64287"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_category?post=64287"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_skills?post=64287"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_tags?post=64287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}