{"id":63060,"date":"2022-08-15T12:21:57","date_gmt":"2022-08-15T10:21:57","guid":{"rendered":"https:\/\/ehrler-beck.tiaro.eu\/?post_type=beundeh_portfolio&#038;p=63060"},"modified":"2022-08-15T12:23:24","modified_gmt":"2022-08-15T10:23:24","slug":"t-4-40-dsk-druck-vakuumpumpen","status":"publish","type":"tirenoa_portfolio","link":"https:\/\/ehrler-beck.com\/de\/produkt\/t-4-40-dsk-druck-vakuumpumpen","title":{"rendered":"T 4.40 DSK Druck-Vakuumpumpen"},"content":{"rendered":"<p>Die robust aufgebauten Drehschieberpumpe T 4.40 DSK ist f\u00fcr h\u00f6here Druckdifferenzen in Vakuum- und\/oder Druckanwendungen geeignet. In einem zylindrischen Geh\u00e4use dreht sich ein exzentrisch gelagerter Rotor mit Schlitzen, in denen sich passgenaue Schieber bewegen und die einzelnen Arbeitskammern voneinander trennen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die robust aufgebauten Drehschieberpumpe T 4.40 DSK ist f\u00fcr h\u00f6here Druckdifferenzen in Vakuum- und\/oder Druckanwendungen geeignet. In einem zylindrischen Geh\u00e4use dreht sich ein exzentrisch gelagerter Rotor mit Schlitzen, in denen sich passgenaue Schieber bewegen und die einzelnen Arbeitskammern voneinander trennen.<\/p>\n","protected":false},"author":1,"featured_media":63061,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[2452],"portfolio_skills":[437],"portfolio_tags":[920],"class_list":["post-63060","tirenoa_portfolio","type-tirenoa_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-t-dvt-serie","portfolio_skills-becker","portfolio_tags-oelfrei-drehschieber-druck-vakuumpumpen"],"acf":[],"_links":{"self":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio\/63060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio"}],"about":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/types\/tirenoa_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/comments?post=63060"}],"version-history":[{"count":0,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio\/63060\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/media\/63061"}],"wp:attachment":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/media?parent=63060"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_category?post=63060"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_skills?post=63060"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_tags?post=63060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}