{"id":62887,"date":"2022-08-15T06:48:42","date_gmt":"2022-08-15T04:48:42","guid":{"rendered":"https:\/\/ehrler-beck.tiaro.eu\/?post_type=beundeh_portfolio&#038;p=62887"},"modified":"2022-08-15T06:48:42","modified_gmt":"2022-08-15T04:48:42","slug":"seco-dc-0080-b-druck-vakuumpumpen","status":"publish","type":"tirenoa_portfolio","link":"https:\/\/ehrler-beck.com\/de\/produkt\/seco-dc-0080-b-druck-vakuumpumpen","title":{"rendered":"SECO DC 0080 B Druck-Vakuumpumpen"},"content":{"rendered":"<p>Seco DC 0080 B Drehschieber-Druck-Vakuumpumpe arbeiten nach dem bew\u00e4hrten Drehschieber-Funktionsprinzip. Da die Rotorfl\u00fcgel selbstschmierend sind, sind keine Betriebsfl\u00fcssigkeiten erforderlich und die Verdichtung erfolgt vollst\u00e4ndig trocken. Serienm\u00e4\u00dfig eingebaute integrierte Filterelemente sch\u00fctzen die Pumpe vor Verunreinigungen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seco DC 0080 B Drehschieber-Druck-Vakuumpumpe arbeiten nach dem bew\u00e4hrten Drehschieber-Funktionsprinzip. Da die Rotorfl\u00fcgel selbstschmierend sind, sind keine Betriebsfl\u00fcssigkeiten erforderlich und die Verdichtung erfolgt vollst\u00e4ndig trocken. Serienm\u00e4\u00dfig eingebaute integrierte Filterelemente sch\u00fctzen die Pumpe vor Verunreinigungen.<\/p>\n","protected":false},"author":1,"featured_media":62889,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[2445],"portfolio_skills":[439],"portfolio_tags":[920],"class_list":["post-62887","tirenoa_portfolio","type-tirenoa_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-seco-dc-serie","portfolio_skills-busch-produkte","portfolio_tags-oelfrei-drehschieber-druck-vakuumpumpen"],"acf":[],"_links":{"self":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio\/62887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio"}],"about":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/types\/tirenoa_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/comments?post=62887"}],"version-history":[{"count":0,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio\/62887\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/media\/62889"}],"wp:attachment":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/media?parent=62887"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_category?post=62887"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_skills?post=62887"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_tags?post=62887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}