{"id":62510,"date":"2022-08-13T18:47:57","date_gmt":"2022-08-13T16:47:57","guid":{"rendered":"https:\/\/ehrler-beck.tiaro.eu\/?post_type=beundeh_portfolio&#038;p=62510"},"modified":"2022-08-13T18:47:57","modified_gmt":"2022-08-13T16:47:57","slug":"dt-4-25-k-oelfrei-drehschieber-verdichter","status":"publish","type":"tirenoa_portfolio","link":"https:\/\/ehrler-beck.com\/de\/produkt\/dt-4-25-k-oelfrei-drehschieber-verdichter","title":{"rendered":"DT 4.25 K \u00d6lfrei Drehschieber-Verdichter"},"content":{"rendered":"<p>DT 4.25 K beinhaltet einen integrierten Saugfilter, ein Druckregelventil und eine Luftd\u00fcse. V\u00f6llig \u00f6lfreier Betrieb. Einzelkammer durch langlebige Fl\u00fcgel getrennt. Geringe Wartungs- und Betriebskosten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DT 4.25 K beinhaltet einen integrierten Saugfilter, ein Druckregelventil und eine Luftd\u00fcse. V\u00f6llig \u00f6lfreier Betrieb. Einzelkammer durch langlebige Fl\u00fcgel getrennt. Geringe Wartungs- und Betriebskosten.<\/p>\n","protected":false},"author":1,"featured_media":62511,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[2403],"portfolio_skills":[437],"portfolio_tags":[2406],"class_list":["post-62510","tirenoa_portfolio","type-tirenoa_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-dt-kdt-dtlf-serie","portfolio_skills-becker","portfolio_tags-drehschieber-verdichter"],"acf":[],"_links":{"self":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio\/62510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio"}],"about":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/types\/tirenoa_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/comments?post=62510"}],"version-history":[{"count":0,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio\/62510\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/media\/62511"}],"wp:attachment":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/media?parent=62510"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_category?post=62510"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_skills?post=62510"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_tags?post=62510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}