{"id":61964,"date":"2022-08-12T09:42:29","date_gmt":"2022-08-12T07:42:29","guid":{"rendered":"https:\/\/ehrler-beck.tiaro.eu\/?post_type=beundeh_portfolio&#038;p=61964"},"modified":"2022-08-12T09:42:29","modified_gmt":"2022-08-12T07:42:29","slug":"g-bh1-2bh1-510-geblaese","status":"publish","type":"tirenoa_portfolio","link":"https:\/\/ehrler-beck.com\/de\/produkt\/g-bh1-2bh1-510-geblaese","title":{"rendered":"G-BH1 2BH1 510 Gebl\u00e4se"},"content":{"rendered":"<p>Das Gebl\u00e4se G-BH1 510 ist zuverl\u00e4ssig, langlebig und wartungsarm. G-BH1 Gebl\u00e4se haben einen hohen Ansaugvolumenstrom von bis zu 2.500 m\u00b3\/h und einen Differenzdruck von bis zu 780 mbar. Seitenkanalverdichter G-BH1 von Elmo Rietschle haben sich ihren Ruf redlich verdient. Gebl\u00e4se der Baureihe G-BH1 k\u00f6nnen bis zu 20000 Betriebsstunden st\u00f6rungsfrei leisten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Gebl\u00e4se G-BH1 510 ist zuverl\u00e4ssig, langlebig und wartungsarm. G-BH1 Gebl\u00e4se haben einen hohen Ansaugvolumenstrom von bis zu 2.500 m\u00b3\/h und einen Differenzdruck von bis zu 780 mbar. Seitenkanalverdichter G-BH1 von Elmo Rietschle haben sich ihren Ruf redlich verdient. Gebl\u00e4se der Baureihe G-BH1 k\u00f6nnen bis zu 20000 Betriebsstunden st\u00f6rungsfrei leisten.<\/p>\n","protected":false},"author":1,"featured_media":61966,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[923],"portfolio_skills":[441],"portfolio_tags":[924,1965],"class_list":["post-61964","tirenoa_portfolio","type-tirenoa_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-g-serie","portfolio_skills-elmo-rietschle-produkte","portfolio_tags-seitenkanal-vakuumpumpen","portfolio_tags-seitenkanal-verdichter"],"acf":[],"_links":{"self":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio\/61964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio"}],"about":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/types\/tirenoa_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/comments?post=61964"}],"version-history":[{"count":0,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio\/61964\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/media\/61966"}],"wp:attachment":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/media?parent=61964"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_category?post=61964"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_skills?post=61964"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_tags?post=61964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}