{"id":61269,"date":"2022-08-08T17:05:46","date_gmt":"2022-08-08T15:05:46","guid":{"rendered":"https:\/\/ehrler-beck.tiaro.eu\/?post_type=beundeh_portfolio&#038;p=61269"},"modified":"2022-08-08T17:05:46","modified_gmt":"2022-08-08T15:05:46","slug":"samos-si-0150-e1-geblaese","status":"publish","type":"tirenoa_portfolio","link":"https:\/\/ehrler-beck.com\/de\/produkt\/samos-si-0150-e1-geblaese","title":{"rendered":"SAMOS SI 0150 E1 Gebl\u00e4se"},"content":{"rendered":"<p>Samos SI 0150 E1 sind die idealen Seitenkanalgebl\u00e4se f\u00fcr den Unterdruck- und \u00dcberdruckbereich. Samos SI Seitenkanalgebl\u00e4se sind durch die trockene Verdichtung und den energieeffizienten Antriebsmotor \u00e4u\u00dferst wirtschaftlich und umweltfreundlich.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Samos SI 0150 E1 sind die idealen Seitenkanalgebl\u00e4se f\u00fcr den Unterdruck- und \u00dcberdruckbereich. Samos SI Seitenkanalgebl\u00e4se sind durch die trockene Verdichtung und den energieeffizienten Antriebsmotor \u00e4u\u00dferst wirtschaftlich und umweltfreundlich.<\/p>\n","protected":false},"author":1,"featured_media":61270,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[2095],"portfolio_skills":[439],"portfolio_tags":[924,1965],"class_list":["post-61269","tirenoa_portfolio","type-tirenoa_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-samos-serie","portfolio_skills-busch-produkte","portfolio_tags-seitenkanal-vakuumpumpen","portfolio_tags-seitenkanal-verdichter"],"acf":[],"_links":{"self":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio\/61269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio"}],"about":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/types\/tirenoa_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/comments?post=61269"}],"version-history":[{"count":0,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio\/61269\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/media\/61270"}],"wp:attachment":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/media?parent=61269"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_category?post=61269"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_skills?post=61269"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_tags?post=61269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}