{"id":60646,"date":"2022-08-07T12:47:27","date_gmt":"2022-08-07T10:47:27","guid":{"rendered":"https:\/\/ehrler-beck.tiaro.eu\/?post_type=beundeh_portfolio&#038;p=60646"},"modified":"2022-08-07T12:47:27","modified_gmt":"2022-08-07T10:47:27","slug":"ruvac-wsu-2001-vakuumpumpe","status":"publish","type":"tirenoa_portfolio","link":"https:\/\/ehrler-beck.com\/de\/produkt\/ruvac-wsu-2001-vakuumpumpe","title":{"rendered":"RUVAC WSU 2001 Vakuumpumpe"},"content":{"rendered":"<p>RUVAC WSU 2001 l\u00e4sst sich problemlos von senkrechten zu horizontalen Pumpvorg\u00e4ngen umbauen. Zum Absaugen oder Pumpen von hochreinen oder radioaktiven Gasen, Reinr\u00e4umen und f\u00fcr Anwendungen, die eine hohe Pumpgeschwindigkeit erfordern. RUVAC WSU ist besonders dicht, da keine Schachtdurchf\u00fchrung in die Atmosph\u00e4re erfolgt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RUVAC WSU 2001 l\u00e4sst sich problemlos von senkrechten zu horizontalen Pumpvorg\u00e4ngen umbauen. Zum Absaugen oder Pumpen von hochreinen oder radioaktiven Gasen, Reinr\u00e4umen und f\u00fcr Anwendungen, die eine hohe Pumpgeschwindigkeit erfordern. RUVAC WSU ist besonders dicht, da keine Schachtdurchf\u00fchrung in die Atmosph\u00e4re erfolgt.<\/p>\n","protected":false},"author":1,"featured_media":60608,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[1910],"portfolio_skills":[438],"portfolio_tags":[930],"class_list":["post-60646","tirenoa_portfolio","type-tirenoa_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-ruvac-serie","portfolio_skills-leybold-produkte","portfolio_tags-waelzkolben-vakuumpumpen"],"acf":[],"_links":{"self":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio\/60646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio"}],"about":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/types\/tirenoa_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/comments?post=60646"}],"version-history":[{"count":0,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio\/60646\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/media\/60608"}],"wp:attachment":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/media?parent=60646"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_category?post=60646"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_skills?post=60646"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_tags?post=60646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}