{"id":59879,"date":"2022-08-05T07:41:37","date_gmt":"2022-08-05T05:41:37","guid":{"rendered":"https:\/\/ehrler-beck.tiaro.eu\/?post_type=beundeh_portfolio&#038;p=59879"},"modified":"2022-08-05T07:41:37","modified_gmt":"2022-08-05T05:41:37","slug":"s-vsi-twister-100-vakuumpumpe","status":"publish","type":"tirenoa_portfolio","link":"https:\/\/ehrler-beck.com\/de\/produkt\/s-vsi-twister-100-vakuumpumpe","title":{"rendered":"S-VSI TWISTER 100 Vakuumpumpe"},"content":{"rendered":"<p>Schraubenrotoren mit variabler Steigung. Wellenabdichtungen mittels Labyrinthdichtung, Wellendichtringen und Kolbenringdichtung. Sperrgas-Beaufschlagung optional. Niedriges Ger\u00e4uschniveau und niedrige Temperaturen, einfache Wartung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schraubenrotoren mit variabler Steigung. Wellenabdichtungen mittels Labyrinthdichtung, Wellendichtringen und Kolbenringdichtung. Sperrgas-Beaufschlagung optional. Niedriges Ger\u00e4uschniveau und niedrige Temperaturen, einfache Wartung.<\/p>\n","protected":false},"author":1,"featured_media":59866,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[1856],"portfolio_skills":[441],"portfolio_tags":[927],"class_list":["post-59879","tirenoa_portfolio","type-tirenoa_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-s-serie","portfolio_skills-elmo-rietschle-produkte","portfolio_tags-schrauben-vakuumpumpen"],"acf":[],"_links":{"self":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio\/59879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio"}],"about":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/types\/tirenoa_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/comments?post=59879"}],"version-history":[{"count":0,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio\/59879\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/media\/59866"}],"wp:attachment":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/media?parent=59879"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_category?post=59879"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_skills?post=59879"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_tags?post=59879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}