{"id":59817,"date":"2022-08-04T22:13:09","date_gmt":"2022-08-04T20:13:09","guid":{"rendered":"https:\/\/ehrler-beck.tiaro.eu\/?post_type=beundeh_portfolio&#038;p=59817"},"modified":"2022-08-04T22:13:09","modified_gmt":"2022-08-04T20:13:09","slug":"s-vsb-twister-200-vakuumpumpe","status":"publish","type":"tirenoa_portfolio","link":"https:\/\/ehrler-beck.com\/de\/produkt\/s-vsb-twister-200-vakuumpumpe","title":{"rendered":"S-VSB TWISTER 200 Vakuumpumpe"},"content":{"rendered":"<p>Hochbest\u00e4ndige Wellenabdichtungen dank doppelt wirkenden PTFE-Wellendichtringen und einfach wirkender Gleitringdichtung, Sperrgas-Beaufschlagung optional. Niedriges Ger\u00e4uschniveau und niedrige Temperaturen, einfache Wartung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hochbest\u00e4ndige Wellenabdichtungen dank doppelt wirkenden PTFE-Wellendichtringen und einfach wirkender Gleitringdichtung, Sperrgas-Beaufschlagung optional. Niedriges Ger\u00e4uschniveau und niedrige Temperaturen, einfache Wartung.<\/p>\n","protected":false},"author":1,"featured_media":59806,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[1856],"portfolio_skills":[441],"portfolio_tags":[927],"class_list":["post-59817","tirenoa_portfolio","type-tirenoa_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-s-serie","portfolio_skills-elmo-rietschle-produkte","portfolio_tags-schrauben-vakuumpumpen"],"acf":[],"_links":{"self":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio\/59817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio"}],"about":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/types\/tirenoa_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/comments?post=59817"}],"version-history":[{"count":0,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio\/59817\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/media\/59806"}],"wp:attachment":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/media?parent=59817"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_category?post=59817"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_skills?post=59817"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_tags?post=59817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}