{"id":58979,"date":"2022-08-02T21:12:06","date_gmt":"2022-08-02T19:12:06","guid":{"rendered":"https:\/\/ehrler-beck.tiaro.eu\/?post_type=beundeh_portfolio&#038;p=58979"},"modified":"2022-08-02T21:12:06","modified_gmt":"2022-08-02T19:12:06","slug":"sc-40-vakuumpumpe","status":"publish","type":"tirenoa_portfolio","link":"https:\/\/ehrler-beck.com\/de\/produkt\/sc-40-vakuumpumpe","title":{"rendered":"SC 40 Vakuumpumpe"},"content":{"rendered":"<p>Die \u00f6lfreie Drehschieber-Vakuumpumpe SC 40 ist am Einlass mit einem Schutzfilter ausgestattet. Begrenztes Gewicht und Abmessungen sind durch das Monoblock-Industriedesign m\u00f6glich, bei dem der Rotor direkt auf der Motorwelle montiert ist. Gebaut mit leichten Legierungen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die \u00f6lfreie Drehschieber-Vakuumpumpe SC 40 ist am Einlass mit einem Schutzfilter ausgestattet. Begrenztes Gewicht und Abmessungen sind durch das Monoblock-Industriedesign m\u00f6glich, bei dem der Rotor direkt auf der Motorwelle montiert ist. Gebaut mit leichten Legierungen.<\/p>\n","protected":false},"author":1,"featured_media":58980,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[1763],"portfolio_skills":[1762],"portfolio_tags":[1713],"class_list":["post-58979","tirenoa_portfolio","type-tirenoa_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-sc-serie","portfolio_skills-dvp","portfolio_tags-drehschieber-vakuumpumpen-oelfrei"],"acf":[],"_links":{"self":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio\/58979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio"}],"about":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/types\/tirenoa_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/comments?post=58979"}],"version-history":[{"count":0,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio\/58979\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/media\/58980"}],"wp:attachment":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/media?parent=58979"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_category?post=58979"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_skills?post=58979"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_tags?post=58979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}