{"id":54393,"date":"2022-05-12T18:07:34","date_gmt":"2022-05-12T16:07:34","guid":{"rendered":"https:\/\/ehrler-beck.tiaro.eu\/?post_type=beundeh_portfolio&#038;p=54393"},"modified":"2022-05-12T18:10:27","modified_gmt":"2022-05-12T16:10:27","slug":"sv-500-1-variair-vakuumpumpen","status":"publish","type":"tirenoa_portfolio","link":"https:\/\/ehrler-beck.com\/de\/produkt\/sv-500-1-variair-vakuumpumpen","title":{"rendered":"SV 500\/1 VariAir-Vakuumpumpen"},"content":{"rendered":"<p>Das VARIAIR SV 500\/1 ist ein einstufiges Regenerativgebl\u00e4se mit variabler Frequenz, das eine hohe Leistung in einer ruhigen, ber\u00fchrungslosen Umgebung bietet. 100 % \u00f6l- und ber\u00fchrungsfrei im Betrieb sind diese Pumpen wartungsarm, hocheffizient und ben\u00f6tigen nur minimale Wartung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das VARIAIR SV 500\/1 ist ein einstufiges Regenerativgebl\u00e4se mit variabler Frequenz, das eine hohe Leistung in einer ruhigen, ber\u00fchrungslosen Umgebung bietet. 100 % \u00f6l- und ber\u00fchrungsfrei im Betrieb sind diese Pumpen wartungsarm, hocheffizient und ben\u00f6tigen nur minimale Wartung.<\/p>\n","protected":false},"author":1,"featured_media":54131,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[1613],"portfolio_skills":[437],"portfolio_tags":[924],"class_list":["post-54393","tirenoa_portfolio","type-tirenoa_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-sv-serie","portfolio_skills-becker","portfolio_tags-seitenkanal-vakuumpumpen"],"acf":[],"_links":{"self":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio\/54393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio"}],"about":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/types\/tirenoa_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/comments?post=54393"}],"version-history":[{"count":0,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio\/54393\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/media\/54131"}],"wp:attachment":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/media?parent=54393"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_category?post=54393"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_skills?post=54393"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_tags?post=54393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}