{"id":13756,"date":"2018-11-28T13:28:03","date_gmt":"2018-11-28T12:28:03","guid":{"rendered":"https:\/\/ehrler-beck.tiaro.eu\/?post_type=avada_portfolio&#038;p=13756"},"modified":"2020-12-31T09:37:07","modified_gmt":"2020-12-31T08:37:07","slug":"v-vcb-25-vakuumpumpe","status":"publish","type":"tirenoa_portfolio","link":"https:\/\/ehrler-beck.com\/de\/produkt\/v-vcb-25-vakuumpumpe","title":{"rendered":"V-VCB 25 Vakuumpumpe"},"content":{"rendered":"<p><span class=\"intro-text\">Die \u00f6lgeschmierte Drehschieber-Vakuumpumpe V-VCB 25 wurde speziell f\u00fcr den Einbau in kleine Vakuumverpackungsmaschinen konzipiert. Flanschmotor mit Lagern auf beiden Seiten des Rotors ist luftgek\u00fchlt. Ausgestattet mit einem feinen Netzfilter, Vakuum-R\u00fcckschlagventil und \u00d6labscheider.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die \u00f6lgeschmierte Drehschieber-Vakuumpumpe V-VCB 25 wurde speziell f\u00fcr den Einbau in kleine Vakuumverpackungsmaschinen konzipiert. Flanschmotor mit Lagern<\/p>\n","protected":false},"author":1,"featured_media":13759,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[436],"portfolio_skills":[441,440],"portfolio_tags":[548],"class_list":["post-13756","tirenoa_portfolio","type-tirenoa_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-v-serie","portfolio_skills-elmo-rietschle-produkte","portfolio_skills-gardner-denver-produkte","portfolio_tags-drehschieber-vakuumpumpen-olgeschmiert"],"acf":[],"_links":{"self":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio\/13756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio"}],"about":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/types\/tirenoa_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/comments?post=13756"}],"version-history":[{"count":0,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/tirenoa_portfolio\/13756\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/media\/13759"}],"wp:attachment":[{"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/media?parent=13756"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_category?post=13756"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_skills?post=13756"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/ehrler-beck.com\/de\/wp-json\/wp\/v2\/portfolio_tags?post=13756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}